{"id":13191,"date":"2021-12-29T16:23:31","date_gmt":"2021-12-29T15:23:31","guid":{"rendered":"https:\/\/vigilant.es\/die-chipkrise\/"},"modified":"2022-06-29T16:28:51","modified_gmt":"2022-06-29T14:28:51","slug":"die-chipkrise","status":"publish","type":"post","link":"https:\/\/vigilant.es\/de\/die-chipkrise\/","title":{"rendered":"Die Chipkrise"},"content":{"rendered":"<div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 fusion-flex-container nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start fusion-flex-content-wrap\" style=\"max-width:1216.8px;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_1_1 1_1 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:0px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-text fusion-text-1\" style=\"--awb-text-transform:none;\"><p><span style=\"font-weight: 400;\">Ein harter Wettbewerb zwischen den verschiedenen Herstellern hat uns an eine permanente Weiterentwicklung der F\u00e4higkeiten der Komponenten gew\u00f6hnt. Immer leistungsf\u00e4higer, bei geringerem Verbrauch und zu einem g\u00fcnstigeren Preis. Dadurch konnten wir Technologien implementieren, die es uns unter anderem erm\u00f6glichen, Ger\u00e4te drahtlos zu verbinden, Maschinen mit Rechenkapazit\u00e4t und k\u00fcnstlicher Intelligenz auszustatten, die Elektromotoren von Fahrzeugen effektiv zu steuern, verbrauchsarme LED-Beleuchtung effizient zu nutzen und vieles mehr. Doch pl\u00f6tzlich ist die Grundlage dieses Marktes und die weltweite Verf\u00fcgbarkeit dieser Komponenten zu niedrigen Preisen verschwunden.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Der Ursprung dieses Mangels scheint in einem gemeinsamen Element zu liegen, das alle Unternehmen ben\u00f6tigen, die elektronische Komponenten herstellen: Siliziumwafer. Es ist ein Grundmaterial, aus dem jeder Hersteller seine Komponenten herstellt.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Es gibt nur sehr wenige Hersteller von Siliziumwafern und die Fabriken sind komplex. Es ist nicht einfach, die Produktion in kurzer Zeit zu duplizieren, also hat der Markt das getan, was er am besten kann: auf Dinge spekulieren, die knapp sind. Die gleichen Hersteller von elektronischen Komponenten werden zu Brokern. Da h\u00f6rt man S\u00e4tze wie \u201eDu musst es kaufen, weil es morgen teurer wird\u201c. Klingt es nach etwas f\u00fcr Sie? Irgendeine Blase, in der wir vorher gelebt haben?<\/span><\/p>\n<p><strong>Je komplexer die Maschine, desto mehr elektronische Komponenten hat sie und desto wahrscheinlicher ist es, dass einige davon nicht verf\u00fcgbar sind oder ihr Preis auf unerschwingliche Werte gestiegen ist.<\/strong><\/p>\n<p><span style=\"font-weight: 400;\"><strong>Wann normalisiert sich das? Die Wahrheit ist, dass niemand es wei\u00df.<\/strong> F\u00fcr 2022 haben wir lange Lieferzeiten und nat\u00fcrlich eine generelle Preiserh\u00f6hung. Die Laufzeiten k\u00f6nnen sich nach und nach verk\u00fcrzen, aber Preiserh\u00f6hungen sind in der Regel von Dauer. Und das kann erhebliche Auswirkungen auf die Kosten f\u00fcr alles haben, was wir mit Elektronik kaufen. Was auf fast alles hinausl\u00e4uft, au\u00dfer was wir essen und was wir tragen.<\/span><\/p>\n<p><img decoding=\"async\" class=\" wp-image-10912 aligncenter\" src=\"https:\/\/vigilant.es\/wp-content\/uploads\/2021\/12\/image010.jpg\" alt=\" VIGILANT - Control Presencia y Horario\" width=\"473\" height=\"378\" srcset=\"https:\/\/vigilant.es\/wp-content\/uploads\/2021\/12\/image010-177x142.jpg 177w, https:\/\/vigilant.es\/wp-content\/uploads\/2021\/12\/image010-200x160.jpg 200w, https:\/\/vigilant.es\/wp-content\/uploads\/2021\/12\/image010-300x240.jpg 300w, https:\/\/vigilant.es\/wp-content\/uploads\/2021\/12\/image010-400x320.jpg 400w, https:\/\/vigilant.es\/wp-content\/uploads\/2021\/12\/image010.jpg 600w\" sizes=\"(max-width: 473px) 100vw, 473px\" \/><\/p>\n<h3><strong>Vigilant \u2013 Kontrolle von Anwesenheit und Zeitplan<\/strong><\/h3>\n<p><span style=\"font-weight: 400;\">Bei VIGILANT \u2013 Anwesenheits- und Zeitkontrolle stellen wir seit 1994 kontinuierlich unsere eigenen Ger\u00e4te her, haupts\u00e4chlich mit nationalen Lieferanten, viele davon in der Provinz Alicante.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Und ja, wir sind nat\u00fcrlich von der Preissteigerung und den Lieferzeiten der Bauteile betroffen, die aus Asien kommen, aber wir k\u00f6nnen unsere Produktionsprozesse mit den weiter verbreiteten \u201eChips\u201c anpassen, mit dem Ziel, die Preise zu halten, Qualit\u00e4t und Lieferzeiten.<\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"font-weight: 400;\">Nun stellt sich heraus, dass es von Vorteil sein kann, vor Ort zu produzieren.<\/span><\/p>\n<\/div><div style=\"text-align:center;\"><a class=\"fusion-button button-flat fusion-button-default-size button-default fusion-button-default button-1 fusion-button-default-span fusion-button-default-type\" target=\"_self\" href=\"https:\/\/vigilant.es\/de\/\"><span class=\"fusion-button-text awb-button__text awb-button__text--default\">VIGILANT<\/span><\/a><\/div><\/div><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Ein harter Wettbewerb zwischen den verschiedenen Herstellern hat uns an eine permanente Weiterentwicklung der F\u00e4higkeiten der Komponenten gew\u00f6hnt. Immer leistungsf\u00e4higer, bei geringerem Verbrauch und zu einem g\u00fcnstigeren Preis. Dadurch konnten wir Technologien implementieren, die es uns unter anderem erm\u00f6glichen, Ger\u00e4te drahtlos zu verbinden, Maschinen mit Rechenkapazit\u00e4t und k\u00fcnstlicher Intelligenz auszustatten, die Elektromotoren von Fahrzeugen effektiv zu steuern, verbrauchsarme LED-Beleuchtung effizient zu nutzen und vieles mehr. Doch pl\u00f6tzlich ist die Grundlage dieses Marktes und die weltweite Verf\u00fcgbarkeit dieser Komponenten zu niedrigen Preisen verschwunden.<\/p>\n","protected":false},"author":21,"featured_media":10918,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","footnotes":""},"categories":[1944],"tags":[],"class_list":["post-13191","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-unkategorisiert"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Die Chipkrise | Vigilant - Kontrolle von Anwesenheit und Zeitplan<\/title>\n<meta name=\"description\" content=\"Bei VIGILANT \u2013 Anwesenheits- und Zeitkontrolle stellen wir seit 1994 kontinuierlich unsere eigenen Ger\u00e4te her\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/vigilant.es\/de\/die-chipkrise\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Die Chipkrise | Vigilant - Kontrolle von Anwesenheit und Zeitplan\" \/>\n<meta property=\"og:description\" content=\"Bei VIGILANT \u2013 Anwesenheits- und Zeitkontrolle stellen wir seit 1994 kontinuierlich unsere eigenen Ger\u00e4te her\" \/>\n<meta property=\"og:url\" content=\"https:\/\/vigilant.es\/de\/die-chipkrise\/\" \/>\n<meta property=\"og:site_name\" content=\"Vigilant | Control Horario\" \/>\n<meta property=\"article:published_time\" content=\"2021-12-29T15:23:31+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-06-29T14:28:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/vigilant.es\/wp-content\/uploads\/2021\/12\/redes-sociales-vigilant.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"940\" \/>\n\t<meta property=\"og:image:height\" content=\"788\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"soltra@vigilant.es\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"soltra@vigilant.es\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"4\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/vigilant.es\\\/de\\\/die-chipkrise\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vigilant.es\\\/de\\\/die-chipkrise\\\/\"},\"author\":{\"name\":\"soltra@vigilant.es\",\"@id\":\"https:\\\/\\\/vigilant.es\\\/de\\\/#\\\/schema\\\/person\\\/7d79e09ca316090a567cd44ce2cc39c9\"},\"headline\":\"Die Chipkrise\",\"datePublished\":\"2021-12-29T15:23:31+00:00\",\"dateModified\":\"2022-06-29T14:28:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/vigilant.es\\\/de\\\/die-chipkrise\\\/\"},\"wordCount\":800,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/vigilant.es\\\/de\\\/die-chipkrise\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/vigilant.es\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/redes-sociales-vigilant.jpg\",\"articleSection\":[\"Blog Vigilant\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/vigilant.es\\\/de\\\/die-chipkrise\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/vigilant.es\\\/de\\\/die-chipkrise\\\/\",\"url\":\"https:\\\/\\\/vigilant.es\\\/de\\\/die-chipkrise\\\/\",\"name\":\"Die Chipkrise | Vigilant - Kontrolle von Anwesenheit und Zeitplan\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vigilant.es\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/vigilant.es\\\/de\\\/die-chipkrise\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/vigilant.es\\\/de\\\/die-chipkrise\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/vigilant.es\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/redes-sociales-vigilant.jpg\",\"datePublished\":\"2021-12-29T15:23:31+00:00\",\"dateModified\":\"2022-06-29T14:28:51+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/vigilant.es\\\/de\\\/#\\\/schema\\\/person\\\/7d79e09ca316090a567cd44ce2cc39c9\"},\"description\":\"Bei VIGILANT \u2013 Anwesenheits- und Zeitkontrolle stellen wir seit 1994 kontinuierlich unsere eigenen Ger\u00e4te her\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/vigilant.es\\\/de\\\/die-chipkrise\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/vigilant.es\\\/de\\\/die-chipkrise\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/vigilant.es\\\/de\\\/die-chipkrise\\\/#primaryimage\",\"url\":\"https:\\\/\\\/vigilant.es\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/redes-sociales-vigilant.jpg\",\"contentUrl\":\"https:\\\/\\\/vigilant.es\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/redes-sociales-vigilant.jpg\",\"width\":940,\"height\":788,\"caption\":\"VIGILANT - Control Presencia y Horario\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/vigilant.es\\\/de\\\/die-chipkrise\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/vigilant.es\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Die Chipkrise\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/vigilant.es\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/vigilant.es\\\/de\\\/\",\"name\":\"Vigilant | Control Horario\",\"description\":\"Control Horario | Control Horas Empleados\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/vigilant.es\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/vigilant.es\\\/de\\\/#\\\/schema\\\/person\\\/7d79e09ca316090a567cd44ce2cc39c9\",\"name\":\"soltra@vigilant.es\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f5818571c655dc158a04479999ea120799f123df9e0c9fc5090aaeae74f10a6d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f5818571c655dc158a04479999ea120799f123df9e0c9fc5090aaeae74f10a6d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f5818571c655dc158a04479999ea120799f123df9e0c9fc5090aaeae74f10a6d?s=96&d=mm&r=g\",\"caption\":\"soltra@vigilant.es\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Die Chipkrise | Vigilant - Kontrolle von Anwesenheit und Zeitplan","description":"Bei VIGILANT \u2013 Anwesenheits- und Zeitkontrolle stellen wir seit 1994 kontinuierlich unsere eigenen Ger\u00e4te her","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/vigilant.es\/de\/die-chipkrise\/","og_locale":"de_DE","og_type":"article","og_title":"Die Chipkrise | Vigilant - Kontrolle von Anwesenheit und Zeitplan","og_description":"Bei VIGILANT \u2013 Anwesenheits- und Zeitkontrolle stellen wir seit 1994 kontinuierlich unsere eigenen Ger\u00e4te her","og_url":"https:\/\/vigilant.es\/de\/die-chipkrise\/","og_site_name":"Vigilant | Control Horario","article_published_time":"2021-12-29T15:23:31+00:00","article_modified_time":"2022-06-29T14:28:51+00:00","og_image":[{"width":940,"height":788,"url":"https:\/\/vigilant.es\/wp-content\/uploads\/2021\/12\/redes-sociales-vigilant.jpg","type":"image\/jpeg"}],"author":"soltra@vigilant.es","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"soltra@vigilant.es","Gesch\u00e4tzte Lesezeit":"4\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/vigilant.es\/de\/die-chipkrise\/#article","isPartOf":{"@id":"https:\/\/vigilant.es\/de\/die-chipkrise\/"},"author":{"name":"soltra@vigilant.es","@id":"https:\/\/vigilant.es\/de\/#\/schema\/person\/7d79e09ca316090a567cd44ce2cc39c9"},"headline":"Die Chipkrise","datePublished":"2021-12-29T15:23:31+00:00","dateModified":"2022-06-29T14:28:51+00:00","mainEntityOfPage":{"@id":"https:\/\/vigilant.es\/de\/die-chipkrise\/"},"wordCount":800,"commentCount":0,"image":{"@id":"https:\/\/vigilant.es\/de\/die-chipkrise\/#primaryimage"},"thumbnailUrl":"https:\/\/vigilant.es\/wp-content\/uploads\/2021\/12\/redes-sociales-vigilant.jpg","articleSection":["Blog Vigilant"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/vigilant.es\/de\/die-chipkrise\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/vigilant.es\/de\/die-chipkrise\/","url":"https:\/\/vigilant.es\/de\/die-chipkrise\/","name":"Die Chipkrise | Vigilant - Kontrolle von Anwesenheit und Zeitplan","isPartOf":{"@id":"https:\/\/vigilant.es\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/vigilant.es\/de\/die-chipkrise\/#primaryimage"},"image":{"@id":"https:\/\/vigilant.es\/de\/die-chipkrise\/#primaryimage"},"thumbnailUrl":"https:\/\/vigilant.es\/wp-content\/uploads\/2021\/12\/redes-sociales-vigilant.jpg","datePublished":"2021-12-29T15:23:31+00:00","dateModified":"2022-06-29T14:28:51+00:00","author":{"@id":"https:\/\/vigilant.es\/de\/#\/schema\/person\/7d79e09ca316090a567cd44ce2cc39c9"},"description":"Bei VIGILANT \u2013 Anwesenheits- und Zeitkontrolle stellen wir seit 1994 kontinuierlich unsere eigenen Ger\u00e4te her","breadcrumb":{"@id":"https:\/\/vigilant.es\/de\/die-chipkrise\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/vigilant.es\/de\/die-chipkrise\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/vigilant.es\/de\/die-chipkrise\/#primaryimage","url":"https:\/\/vigilant.es\/wp-content\/uploads\/2021\/12\/redes-sociales-vigilant.jpg","contentUrl":"https:\/\/vigilant.es\/wp-content\/uploads\/2021\/12\/redes-sociales-vigilant.jpg","width":940,"height":788,"caption":"VIGILANT - Control Presencia y Horario"},{"@type":"BreadcrumbList","@id":"https:\/\/vigilant.es\/de\/die-chipkrise\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/vigilant.es\/de\/"},{"@type":"ListItem","position":2,"name":"Die Chipkrise"}]},{"@type":"WebSite","@id":"https:\/\/vigilant.es\/de\/#website","url":"https:\/\/vigilant.es\/de\/","name":"Vigilant | Control Horario","description":"Control Horario | Control Horas Empleados","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/vigilant.es\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/vigilant.es\/de\/#\/schema\/person\/7d79e09ca316090a567cd44ce2cc39c9","name":"soltra@vigilant.es","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/f5818571c655dc158a04479999ea120799f123df9e0c9fc5090aaeae74f10a6d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f5818571c655dc158a04479999ea120799f123df9e0c9fc5090aaeae74f10a6d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f5818571c655dc158a04479999ea120799f123df9e0c9fc5090aaeae74f10a6d?s=96&d=mm&r=g","caption":"soltra@vigilant.es"}}]}},"_links":{"self":[{"href":"https:\/\/vigilant.es\/de\/wp-json\/wp\/v2\/posts\/13191","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vigilant.es\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vigilant.es\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vigilant.es\/de\/wp-json\/wp\/v2\/users\/21"}],"replies":[{"embeddable":true,"href":"https:\/\/vigilant.es\/de\/wp-json\/wp\/v2\/comments?post=13191"}],"version-history":[{"count":2,"href":"https:\/\/vigilant.es\/de\/wp-json\/wp\/v2\/posts\/13191\/revisions"}],"predecessor-version":[{"id":13193,"href":"https:\/\/vigilant.es\/de\/wp-json\/wp\/v2\/posts\/13191\/revisions\/13193"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vigilant.es\/de\/wp-json\/wp\/v2\/media\/10918"}],"wp:attachment":[{"href":"https:\/\/vigilant.es\/de\/wp-json\/wp\/v2\/media?parent=13191"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vigilant.es\/de\/wp-json\/wp\/v2\/categories?post=13191"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vigilant.es\/de\/wp-json\/wp\/v2\/tags?post=13191"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}