{"id":2185,"count":0,"description":"","link":"https:\/\/vigilant.es\/en\/tag\/jornada-laboral-en\/","name":"jornada laboral","slug":"jornada-laboral-en","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>jornada laboral archivos - Vigilant | Control Horario<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"jornada laboral archivos - Vigilant | Control Horario\" \/>\n<meta property=\"og:url\" content=\"https:\/\/vigilant.es\/en\/tag\/jornada-laboral-en\/\" \/>\n<meta property=\"og:site_name\" content=\"Vigilant | Control Horario\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/vigilant.es\\\/en\\\/tag\\\/jornada-laboral-en\\\/\",\"url\":\"https:\\\/\\\/vigilant.es\\\/en\\\/tag\\\/jornada-laboral-en\\\/\",\"name\":\"jornada laboral archivos - Vigilant | Control Horario\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vigilant.es\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/vigilant.es\\\/en\\\/tag\\\/jornada-laboral-en\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/vigilant.es\\\/en\\\/tag\\\/jornada-laboral-en\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/vigilant.es\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"jornada laboral\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/vigilant.es\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/vigilant.es\\\/en\\\/\",\"name\":\"Vigilant | Control Horario\",\"description\":\"Control Horario | Control Horas Empleados\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/vigilant.es\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"jornada laboral archivos - Vigilant | Control Horario","robots":{"index":"noindex","follow":"follow"},"og_locale":"en_US","og_type":"article","og_title":"jornada laboral archivos - Vigilant | Control Horario","og_url":"https:\/\/vigilant.es\/en\/tag\/jornada-laboral-en\/","og_site_name":"Vigilant | Control Horario","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/vigilant.es\/en\/tag\/jornada-laboral-en\/","url":"https:\/\/vigilant.es\/en\/tag\/jornada-laboral-en\/","name":"jornada laboral archivos - Vigilant | Control Horario","isPartOf":{"@id":"https:\/\/vigilant.es\/en\/#website"},"breadcrumb":{"@id":"https:\/\/vigilant.es\/en\/tag\/jornada-laboral-en\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/vigilant.es\/en\/tag\/jornada-laboral-en\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/vigilant.es\/en\/"},{"@type":"ListItem","position":2,"name":"jornada laboral"}]},{"@type":"WebSite","@id":"https:\/\/vigilant.es\/en\/#website","url":"https:\/\/vigilant.es\/en\/","name":"Vigilant | Control Horario","description":"Control Horario | Control Horas Empleados","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/vigilant.es\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/vigilant.es\/en\/wp-json\/wp\/v2\/tags\/2185","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vigilant.es\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/vigilant.es\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/vigilant.es\/en\/wp-json\/wp\/v2\/posts?tags=2185"},{"href":"https:\/\/vigilant.es\/en\/wp-json\/wp\/v2\/casos-de-exito?tags=2185"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}