{"id":14541,"date":"2023-03-20T10:51:44","date_gmt":"2023-03-20T09:51:44","guid":{"rendered":"https:\/\/vigilant.es\/manuel-ciges-ceo-co-founder-de-vigilant-incorpora-se-a-junta-diretiva-de-alicantec\/"},"modified":"2023-03-20T10:51:44","modified_gmt":"2023-03-20T09:51:44","slug":"manuel-ciges-ceo-co-founder-de-vigilant-incorpora-se-a-junta-diretiva-de-alicantec","status":"publish","type":"post","link":"https:\/\/vigilant.es\/pt\/manuel-ciges-ceo-co-founder-de-vigilant-incorpora-se-a-junta-diretiva-de-alicantec\/","title":{"rendered":"Manuel Ciges, CEO &#038; Co-founder de Vigilant, incorpora-se \u00e0 junta diretiva de AlicanTec"},"content":{"rendered":"<p><span style=\"font-weight: 400;\">No passado 14 de outubro, Manuel Ciges, CEO &amp; Co-founder de Vigilant, incorporou-se \u00e0 junta directiva de AlicanTec junto com um grande elenco de profissionais do ecosistema alicantino.<\/span><\/p>\n<h3><b>AlicanTec<\/b><\/h3>\n<p><span style=\"font-weight: 400;\">A Associa\u00e7\u00e3o para a Promo\u00e7\u00e3o e Impulso da Tecnolog\u00eda e a Sociedade do Conhecimento de Alicante (AlicanTEC) \u00e9 uma organiza\u00e7\u00e3o sem \u00e1nimo de lucro criada no ano 2016 na cidade de Alicante. A miss\u00e3o de AlicanTEC \u00e9 promover a imagem do Mediterr\u00e1neo sur de Espanha como \u00e1rea de desenvolvimento tecnol\u00f3gico e residencial, mediante uma aposta em valor para startups e empresas tecnol\u00f3gicas internacionais, a explorar um deos h\u00e1bitats de maior qualidade de vida em todo o mundo. Tamb\u00e9m, tratar de favorecer a cultura e o desenvolvimento da economia digital no nosso entorno.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Atualmente est\u00e1 formada por 254 empresas associadas da regi\u00e3o de Alicante, e uma red de 451 amigos da Associa\u00e7\u00e3o espalhados por toda a geografia espanhola e internacional.<\/span><\/p>\n<h5><strong>Nova Organiza\u00e7\u00e3o<\/strong><\/h5>\n<p><span style=\"font-weight: 400;\">A Associa\u00e7\u00e3o para a Promo\u00e7\u00e3o e Impulso da Tecnolog\u00eda e a Sociedade do Conhecimento de Alicante (AlicanTEC) apresentou a nova organiza\u00e7\u00e3o orientada \u00e0 reda\u00e7\u00e3o e execu\u00e7\u00e3o do\u00a0 novo Plano Estrat\u00e9gico 2023-2025, com o objetivo principal de melhorar o setor tecnol\u00f3gico.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">O Presidente de AlicanTec, Antonio S\u00e1nchez Zaplana, e a Vice-presidenta, Aurelia Bustos, t\u00eam desenhado uma nova organiza\u00e7\u00e3o orientada aos retos presente e futuros regionais, adaptada para a cria\u00e7\u00e3o e valida\u00e7\u00e3o do Plano Estrat\u00e9gico. Esta organiza\u00e7\u00e3o permitir\u00e1 al\u00e9m de dar continuidade ao objeto da Associa\u00e7\u00e3o, elevar os resultados e impactos das a\u00e7\u00f5es da mesma.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">A nova organiza\u00e7\u00e3o de AlicanTEC estructura-se em diferentes org\u00e3os de Governo.<\/span><\/p>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Grupo de Alto N\u00edvel, pessoas com relev\u00e2ncia e experi\u00eancia que possam assessorar de forma independente \u00e0 Associa\u00e7\u00e3o desde diferentes \u00e1reas de conhecimento e \u00e2mbitos regionais.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Junta Directiva de AlicanTEC que estar\u00e1 formada por peritos profissionais do ecosistema regional, sendo inclusiva em mat\u00e9ria de representatividade, em tamanho empresarial, territorial e perfis de expertise dos integrantes, onde Manuel Ciges formar\u00e1 parte junto com Trini Mora, Andr\u00e9s Torrubia, Ezequiel S\u00e1nchez, Gala Gil, Gianni Cecchin, Javier Garc\u00eda, Jos\u00e9 Manuel Leceta, Julio S\u00e1nchez, Lasse Rouhiainen, Manuel Bonilla, Manuel Desantes, Maril\u00fa Hern\u00e1ndez, Pedro Pern\u00edas, Jos\u00e9 Mar\u00eda Salinas, Rebecca Rippin, Macu Caruana, Mariam de la Iglesia, Angel Pineda, Germ\u00e1n Gonz\u00e1lez, Alfredo Bataller.<\/span><\/li>\n<\/ul>\n<h3><b>Vigilant<\/b><\/h3>\n<p><span style=\"font-weight: 400;\">Na Vigilant desenhamos, fabricamos e comercializamos produtos e servi\u00e7os espec\u00edficos de Controlo de Presen\u00e7a para ls principais empresas do setor de Seguran\u00e7a e Servi\u00e7os, tanto em Espanha como em Portugal e na atualidade estamos a nos abrir ao mercado exterior.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Formar parte da junta directiva de AlicanTec nos permitir\u00e1 conhecer melhor o ecosistema regional aportando uma vis\u00e3o do resto de empresas espanholas e assim poder sempre oferecermos as melhores solu\u00e7\u00f5es.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>No passado 14 de outubro, Manuel Ciges, CEO &#038; Co-founder de Vigilant, incorporou-se \u00e0 junta directiva de AlicanTec junto com um grande elenco de profissionais do ecosistema alicantino.<\/p>\n","protected":false},"author":21,"featured_media":13873,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","footnotes":""},"categories":[2123],"tags":[],"class_list":["post-14541","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog-vigilant-pt"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Manuel Ciges, CEO &amp; Co-founder de Vigilant, incorpora-se \u00e0 junta diretiva de AlicanTec - Vigilant | Control Horario<\/title>\n<meta name=\"description\" content=\"Manuel Ciges, CEO &amp; Co-founder de Vigilant, incorpora-se \u00e0 junta diretiva de AlicanTec juntamente com profissionais do ecossistema de Alicante\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/vigilant.es\/pt\/manuel-ciges-ceo-co-founder-de-vigilant-incorpora-se-a-junta-diretiva-de-alicantec\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Manuel Ciges, CEO &amp; Co-founder de Vigilant, incorpora-se \u00e0 junta diretiva de AlicanTec - Vigilant | Control Horario\" \/>\n<meta property=\"og:description\" content=\"Manuel Ciges, CEO &amp; Co-founder de Vigilant, incorpora-se \u00e0 junta diretiva de AlicanTec juntamente com profissionais do ecossistema de Alicante\" \/>\n<meta property=\"og:url\" content=\"https:\/\/vigilant.es\/pt\/manuel-ciges-ceo-co-founder-de-vigilant-incorpora-se-a-junta-diretiva-de-alicantec\/\" \/>\n<meta property=\"og:site_name\" content=\"Vigilant | Control Horario\" \/>\n<meta property=\"article:published_time\" content=\"2023-03-20T09:51:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/vigilant.es\/wp-content\/uploads\/2022\/10\/RRSS-VIGILANT-ESPANOL.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"940\" \/>\n\t<meta property=\"og:image:height\" content=\"788\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"soltra@vigilant.es\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"soltra@vigilant.es\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/vigilant.es\\\/pt\\\/manuel-ciges-ceo-co-founder-de-vigilant-incorpora-se-a-junta-diretiva-de-alicantec\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vigilant.es\\\/pt\\\/manuel-ciges-ceo-co-founder-de-vigilant-incorpora-se-a-junta-diretiva-de-alicantec\\\/\"},\"author\":{\"name\":\"soltra@vigilant.es\",\"@id\":\"https:\\\/\\\/vigilant.es\\\/pt\\\/#\\\/schema\\\/person\\\/7d79e09ca316090a567cd44ce2cc39c9\"},\"headline\":\"Manuel Ciges, CEO &#038; Co-founder de Vigilant, incorpora-se \u00e0 junta diretiva de AlicanTec\",\"datePublished\":\"2023-03-20T09:51:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/vigilant.es\\\/pt\\\/manuel-ciges-ceo-co-founder-de-vigilant-incorpora-se-a-junta-diretiva-de-alicantec\\\/\"},\"wordCount\":486,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/vigilant.es\\\/pt\\\/manuel-ciges-ceo-co-founder-de-vigilant-incorpora-se-a-junta-diretiva-de-alicantec\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/vigilant.es\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/RRSS-VIGILANT-ESPANOL.jpg\",\"articleSection\":[\"Blog Vigilant\"],\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/vigilant.es\\\/pt\\\/manuel-ciges-ceo-co-founder-de-vigilant-incorpora-se-a-junta-diretiva-de-alicantec\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/vigilant.es\\\/pt\\\/manuel-ciges-ceo-co-founder-de-vigilant-incorpora-se-a-junta-diretiva-de-alicantec\\\/\",\"url\":\"https:\\\/\\\/vigilant.es\\\/pt\\\/manuel-ciges-ceo-co-founder-de-vigilant-incorpora-se-a-junta-diretiva-de-alicantec\\\/\",\"name\":\"Manuel Ciges, CEO & Co-founder de Vigilant, incorpora-se \u00e0 junta diretiva de AlicanTec - Vigilant | Control Horario\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vigilant.es\\\/pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/vigilant.es\\\/pt\\\/manuel-ciges-ceo-co-founder-de-vigilant-incorpora-se-a-junta-diretiva-de-alicantec\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/vigilant.es\\\/pt\\\/manuel-ciges-ceo-co-founder-de-vigilant-incorpora-se-a-junta-diretiva-de-alicantec\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/vigilant.es\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/RRSS-VIGILANT-ESPANOL.jpg\",\"datePublished\":\"2023-03-20T09:51:44+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/vigilant.es\\\/pt\\\/#\\\/schema\\\/person\\\/7d79e09ca316090a567cd44ce2cc39c9\"},\"description\":\"Manuel Ciges, CEO & Co-founder de Vigilant, incorpora-se \u00e0 junta diretiva de AlicanTec juntamente com profissionais do ecossistema de Alicante\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/vigilant.es\\\/pt\\\/manuel-ciges-ceo-co-founder-de-vigilant-incorpora-se-a-junta-diretiva-de-alicantec\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/vigilant.es\\\/pt\\\/manuel-ciges-ceo-co-founder-de-vigilant-incorpora-se-a-junta-diretiva-de-alicantec\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/vigilant.es\\\/pt\\\/manuel-ciges-ceo-co-founder-de-vigilant-incorpora-se-a-junta-diretiva-de-alicantec\\\/#primaryimage\",\"url\":\"https:\\\/\\\/vigilant.es\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/RRSS-VIGILANT-ESPANOL.jpg\",\"contentUrl\":\"https:\\\/\\\/vigilant.es\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/RRSS-VIGILANT-ESPANOL.jpg\",\"width\":940,\"height\":788,\"caption\":\"Manuel Ciges - Vigilant - Alicantec\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/vigilant.es\\\/pt\\\/manuel-ciges-ceo-co-founder-de-vigilant-incorpora-se-a-junta-diretiva-de-alicantec\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/vigilant.es\\\/pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Manuel Ciges, CEO &#038; Co-founder de Vigilant, incorpora-se \u00e0 junta diretiva de AlicanTec\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/vigilant.es\\\/pt\\\/#website\",\"url\":\"https:\\\/\\\/vigilant.es\\\/pt\\\/\",\"name\":\"Vigilant | Control Horario\",\"description\":\"Control Horario | Control Horas Empleados\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/vigilant.es\\\/pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/vigilant.es\\\/pt\\\/#\\\/schema\\\/person\\\/7d79e09ca316090a567cd44ce2cc39c9\",\"name\":\"soltra@vigilant.es\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f5818571c655dc158a04479999ea120799f123df9e0c9fc5090aaeae74f10a6d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f5818571c655dc158a04479999ea120799f123df9e0c9fc5090aaeae74f10a6d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f5818571c655dc158a04479999ea120799f123df9e0c9fc5090aaeae74f10a6d?s=96&d=mm&r=g\",\"caption\":\"soltra@vigilant.es\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Manuel Ciges, CEO & Co-founder de Vigilant, incorpora-se \u00e0 junta diretiva de AlicanTec - Vigilant | Control Horario","description":"Manuel Ciges, CEO & Co-founder de Vigilant, incorpora-se \u00e0 junta diretiva de AlicanTec juntamente com profissionais do ecossistema de Alicante","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/vigilant.es\/pt\/manuel-ciges-ceo-co-founder-de-vigilant-incorpora-se-a-junta-diretiva-de-alicantec\/","og_locale":"pt_PT","og_type":"article","og_title":"Manuel Ciges, CEO & Co-founder de Vigilant, incorpora-se \u00e0 junta diretiva de AlicanTec - Vigilant | Control Horario","og_description":"Manuel Ciges, CEO & Co-founder de Vigilant, incorpora-se \u00e0 junta diretiva de AlicanTec juntamente com profissionais do ecossistema de Alicante","og_url":"https:\/\/vigilant.es\/pt\/manuel-ciges-ceo-co-founder-de-vigilant-incorpora-se-a-junta-diretiva-de-alicantec\/","og_site_name":"Vigilant | Control Horario","article_published_time":"2023-03-20T09:51:44+00:00","og_image":[{"width":940,"height":788,"url":"https:\/\/vigilant.es\/wp-content\/uploads\/2022\/10\/RRSS-VIGILANT-ESPANOL.jpg","type":"image\/jpeg"}],"author":"soltra@vigilant.es","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"soltra@vigilant.es","Tempo estimado de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/vigilant.es\/pt\/manuel-ciges-ceo-co-founder-de-vigilant-incorpora-se-a-junta-diretiva-de-alicantec\/#article","isPartOf":{"@id":"https:\/\/vigilant.es\/pt\/manuel-ciges-ceo-co-founder-de-vigilant-incorpora-se-a-junta-diretiva-de-alicantec\/"},"author":{"name":"soltra@vigilant.es","@id":"https:\/\/vigilant.es\/pt\/#\/schema\/person\/7d79e09ca316090a567cd44ce2cc39c9"},"headline":"Manuel Ciges, CEO &#038; Co-founder de Vigilant, incorpora-se \u00e0 junta diretiva de AlicanTec","datePublished":"2023-03-20T09:51:44+00:00","mainEntityOfPage":{"@id":"https:\/\/vigilant.es\/pt\/manuel-ciges-ceo-co-founder-de-vigilant-incorpora-se-a-junta-diretiva-de-alicantec\/"},"wordCount":486,"commentCount":0,"image":{"@id":"https:\/\/vigilant.es\/pt\/manuel-ciges-ceo-co-founder-de-vigilant-incorpora-se-a-junta-diretiva-de-alicantec\/#primaryimage"},"thumbnailUrl":"https:\/\/vigilant.es\/wp-content\/uploads\/2022\/10\/RRSS-VIGILANT-ESPANOL.jpg","articleSection":["Blog Vigilant"],"inLanguage":"pt-PT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/vigilant.es\/pt\/manuel-ciges-ceo-co-founder-de-vigilant-incorpora-se-a-junta-diretiva-de-alicantec\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/vigilant.es\/pt\/manuel-ciges-ceo-co-founder-de-vigilant-incorpora-se-a-junta-diretiva-de-alicantec\/","url":"https:\/\/vigilant.es\/pt\/manuel-ciges-ceo-co-founder-de-vigilant-incorpora-se-a-junta-diretiva-de-alicantec\/","name":"Manuel Ciges, CEO & Co-founder de Vigilant, incorpora-se \u00e0 junta diretiva de AlicanTec - Vigilant | Control Horario","isPartOf":{"@id":"https:\/\/vigilant.es\/pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/vigilant.es\/pt\/manuel-ciges-ceo-co-founder-de-vigilant-incorpora-se-a-junta-diretiva-de-alicantec\/#primaryimage"},"image":{"@id":"https:\/\/vigilant.es\/pt\/manuel-ciges-ceo-co-founder-de-vigilant-incorpora-se-a-junta-diretiva-de-alicantec\/#primaryimage"},"thumbnailUrl":"https:\/\/vigilant.es\/wp-content\/uploads\/2022\/10\/RRSS-VIGILANT-ESPANOL.jpg","datePublished":"2023-03-20T09:51:44+00:00","author":{"@id":"https:\/\/vigilant.es\/pt\/#\/schema\/person\/7d79e09ca316090a567cd44ce2cc39c9"},"description":"Manuel Ciges, CEO & Co-founder de Vigilant, incorpora-se \u00e0 junta diretiva de AlicanTec juntamente com profissionais do ecossistema de Alicante","breadcrumb":{"@id":"https:\/\/vigilant.es\/pt\/manuel-ciges-ceo-co-founder-de-vigilant-incorpora-se-a-junta-diretiva-de-alicantec\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/vigilant.es\/pt\/manuel-ciges-ceo-co-founder-de-vigilant-incorpora-se-a-junta-diretiva-de-alicantec\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/vigilant.es\/pt\/manuel-ciges-ceo-co-founder-de-vigilant-incorpora-se-a-junta-diretiva-de-alicantec\/#primaryimage","url":"https:\/\/vigilant.es\/wp-content\/uploads\/2022\/10\/RRSS-VIGILANT-ESPANOL.jpg","contentUrl":"https:\/\/vigilant.es\/wp-content\/uploads\/2022\/10\/RRSS-VIGILANT-ESPANOL.jpg","width":940,"height":788,"caption":"Manuel Ciges - Vigilant - Alicantec"},{"@type":"BreadcrumbList","@id":"https:\/\/vigilant.es\/pt\/manuel-ciges-ceo-co-founder-de-vigilant-incorpora-se-a-junta-diretiva-de-alicantec\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/vigilant.es\/pt\/"},{"@type":"ListItem","position":2,"name":"Manuel Ciges, CEO &#038; Co-founder de Vigilant, incorpora-se \u00e0 junta diretiva de AlicanTec"}]},{"@type":"WebSite","@id":"https:\/\/vigilant.es\/pt\/#website","url":"https:\/\/vigilant.es\/pt\/","name":"Vigilant | Control Horario","description":"Control Horario | Control Horas Empleados","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/vigilant.es\/pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Person","@id":"https:\/\/vigilant.es\/pt\/#\/schema\/person\/7d79e09ca316090a567cd44ce2cc39c9","name":"soltra@vigilant.es","image":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/secure.gravatar.com\/avatar\/f5818571c655dc158a04479999ea120799f123df9e0c9fc5090aaeae74f10a6d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f5818571c655dc158a04479999ea120799f123df9e0c9fc5090aaeae74f10a6d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f5818571c655dc158a04479999ea120799f123df9e0c9fc5090aaeae74f10a6d?s=96&d=mm&r=g","caption":"soltra@vigilant.es"}}]}},"_links":{"self":[{"href":"https:\/\/vigilant.es\/pt\/wp-json\/wp\/v2\/posts\/14541","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vigilant.es\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vigilant.es\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vigilant.es\/pt\/wp-json\/wp\/v2\/users\/21"}],"replies":[{"embeddable":true,"href":"https:\/\/vigilant.es\/pt\/wp-json\/wp\/v2\/comments?post=14541"}],"version-history":[{"count":0,"href":"https:\/\/vigilant.es\/pt\/wp-json\/wp\/v2\/posts\/14541\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vigilant.es\/pt\/wp-json\/wp\/v2\/media\/13873"}],"wp:attachment":[{"href":"https:\/\/vigilant.es\/pt\/wp-json\/wp\/v2\/media?parent=14541"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vigilant.es\/pt\/wp-json\/wp\/v2\/categories?post=14541"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vigilant.es\/pt\/wp-json\/wp\/v2\/tags?post=14541"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}